{"id":126,"date":"2007-12-26T21:29:52","date_gmt":"2007-12-26T21:29:52","guid":{"rendered":"http:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2007\/12\/26\/cosas-que-hice-esta-nochebuena-y-iii\/"},"modified":"2009-05-17T18:20:56","modified_gmt":"2009-05-17T16:20:56","slug":"cosas-que-hice-esta-nochebuena-y-iii","status":"publish","type":"post","link":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2007\/12\/26\/cosas-que-hice-esta-nochebuena-y-iii\/","title":{"rendered":"Cosas que hice esta Nochebuena (y III)"},"content":{"rendered":"<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2007\/12\/nochebuena02.jpg\" title=\"Nochebuena02\" alt=\"La cena de Nochebuena\" width=\"640\" height=\"475\" \/><\/p>\n<p style=\"text-align: justify;\">Finalizando ya los vericuetos de la Nochebuena (<a title=\"La declaraci\u00f3n de intenciones...\" href=\"http:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2007\/12\/18\/cosas-que-hare-esta-nochebuena\/\" target=\"_blank\">I<\/a> y <a title=\"Nochebuena: primer acto\" href=\"http:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2007\/12\/24\/cosas-que-hago-esta-nochebuena-i\/\" target=\"_blank\">II<\/a>), escribo el remate final. Mi prop\u00f3sito era haberlo hecho en tiempo real, pero la cosa se puso algo triste en la entrada anterior y creo que no era momento de caer en lo melodram\u00e1tico. A un tris he estado de borrar la entrada anterior, escrita con el coraz\u00f3n y con el impulso, con mucho de confesi\u00f3n imp\u00fadica. Pero ah\u00ed se va a quedar.<\/p>\n<p style=\"text-align: justify;\">A medida que pasaba la noche, fui traicionando alguno de mis principios. Pero no todos.<\/p>\n<ol style=\"text-align: justify;\">\n<li>Pas\u00e9, en efecto, la noche solo. Y no busqu\u00e9 ni siquiera el refugio del m\u00f3vil m\u00e1s que en un caso m\u00e1s que justificado: hablar con mi hijo. El recuerdo de los ausentes (con el cuerpo -mi padre-  y con la memoria -mi madre-) fue muy doloroso. Tambi\u00e9n lo fue estar separado de mi hijo, que es algo as\u00ed como m\u00e1s de la mitad de m\u00ed. Pero tambi\u00e9n tuvo su parte de consuelo, como se tendr\u00e1 ocasi\u00f3n de comprobar en el punto siguiente.<\/li>\n<li>Primera traici\u00f3n: abr\u00ed una lata de bonito&#8230; pero la mezcl\u00e9 en una ensaladilla. Congelada, eso s\u00ed. Tambi\u00e9n mastiqu\u00e9 despacio. Y a\u00f1ad\u00ed algo que rondaba en el frigor\u00edfico: una sabros\u00edsima carne guisada que estaba haciendo guardia desde la comida.  Y ah\u00ed entr\u00f3 parte del consuelo: no tuve que ver manteles car\u00edsimos conjuntados con velas haciendo juego. No tuve que ver desfilando platos con nombres de cinco l\u00edneas (la chuminada esta de la nueva cocina, que ha recuperado la tradici\u00f3n de los largu\u00edsimos t\u00edtulos de los libros del siglo XVIII). Me perd\u00ed -esa suerte tuve- conversaciones intrascendentes adornadas con pretensiones mil, alejadas de la naturalidad y del sentido com\u00fan. Es decir, me ahorr\u00e9 la parafernalia. Es decir, cen\u00e9 bien.<\/li>\n<li>Vi la tele, pero s\u00f3lo un poquito. Y no exactamente la tele, sino una pel\u00edcula que ten\u00eda grabada. Tengo la costumbre de ver muchas pel\u00edculas en porciones, a veces muy peque\u00f1as.<\/li>\n<li>Escog\u00ed el bonito y tradicional <a href=\"http:\/\/www.flickr.com\/photos\/fordbuchanan\/1136763754\/\" target=\"_blank\">objeto navide\u00f1o<\/a>. Hasta le he dedicado una foto plagiada. Pero no lo exprim\u00ed hasta sus \u00faltimas consecuencias.<\/li>\n<li>Escuch\u00e9 mucha m\u00fasica. Y el <em>iTunes<\/em> en modo aleatorio me depar\u00f3 maravillas (a veces hice trampa, y me salt\u00e9 alguna horterada). As\u00ed que, pese a estar solo, estuve acompa\u00f1ado por Wagner, Mozart, Bach, Diana Krall, Jean Michel Jarre, Miles Davis, Calamaro, Aute, Silvio, Sabina, Eartha Kitt, Gianna Nannini&#8230; Y, en efecto, escuch\u00e9 a Los Secretos: \u00abHoy he so\u00f1ado con otra vida, con otro mundo. Pero a tu lado.\u00bb \u00abYa no persigo sue\u00f1os rotos: los he cosido con el hilo de tus ojos.\u00bb \u00abAhora estoy solo y arrastro mi dolor.\u00bb \u00bb Y mientras en la calle est\u00e1 lloviendo, una tormenta hay en mi coraz\u00f3n\u00bb. Pero el rey de la noche fue John Lennon. Y no pude tener mejor compa\u00f1\u00eda. Escuch\u00e9 la maravilla navide\u00f1a titulada <a title=\"Lennon, siempre.\" href=\"http:\/\/es.youtube.com\/watch?v=oL0JpdIbQFg\" target=\"_blank\">\u00abHappy Christmas (War is over)\u00bb<\/a>. Y muchas otras. Repetidas y repetidas. Siempre diferentes.<\/li>\n<li>Me acord\u00e9 de alguien. Para bien. Para mal. Como reconozco que no soy una hermanita de la caridad, me acord\u00e9 para mal de unos cuantos. Y el tiempo me da la raz\u00f3n. Pero tampoco merecen muchas ideas ni muchas l\u00edneas. Ni en mi cabeza ni en este blog.<\/li>\n<li>No cre\u00ed oportuno escribir una entrada en los minutos pr\u00f3ximos a las doce de la noche. Quiz\u00e1 hubiese puesto cosas de las que me hubiese tenido que arrepentir. Hay mucho bicho por ah\u00ed suelto&#8230;<\/li>\n<li>No me fui a la cama leyendo a  Rilke y sus <a href=\"http:\/\/es.wikipedia.org\/wiki\/Eleg%C3%ADas_de_Duino\" target=\"_blank\"><em>Eleg\u00edas de Duino<\/em><\/a>. Pero s\u00ed me acord\u00e9 a lo largo de la noche de algunos versos, que siempre guardo en alg\u00fan lugar rec\u00f3ndito de mi memoria. Obviamente, no voy a cascarlas aqu\u00ed todas. As\u00ed que el atrevido, que se atreva. S\u00f3lo abrir\u00e9 apetito a los sensibles con el principio: \u00abQui\u00e9n, si yo gritara, me escuchar\u00eda entre los \u00f3rdenes \/ang\u00e9licos?\u00bb \u00abLa belleza no es nada sino el principio de lo terrible\u00bb.<\/li>\n<li>Me fui a la cama. Y le\u00ed, como todos los d\u00edas. Y dorm\u00ed, como todos los d\u00edas. Y esper\u00e9 a que llegase un nuevo d\u00eda, como todos los d\u00edas.<\/li>\n<li>Y ese d\u00eda, afortunadamente, lleg\u00f3. Y, pese a la tristeza, tambi\u00e9n hubo felicidad (o, como le gusta decir a Rojas Marcos, \u00absatisfacci\u00f3n con la vida en general\u00bb). Y de eso hablaremos: de felicidad y de resiliencia. Por extenso. Pero otro d\u00eda.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finalizando ya los vericuetos de la Nochebuena (I y II), escribo el remate final. Mi prop\u00f3sito era haberlo hecho en tiempo real, pero la cosa se puso algo triste en la entrada anterior y creo que no era momento de caer en lo melodram\u00e1tico. A un tris he estado de borrar la entrada anterior, escrita &#8230; <a title=\"Cosas que hice esta Nochebuena (y III)\" class=\"read-more\" href=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2007\/12\/26\/cosas-que-hice-esta-nochebuena-y-iii\/\" aria-label=\"Leer m\u00e1s sobre Cosas que hice esta Nochebuena (y III)\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[37,60,5],"tags":[],"class_list":["post-126","post","type-post","status-publish","format-standard","hentry","category-abismo","category-nochebuena","category-soledad"],"_links":{"self":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/comments?post=126"}],"version-history":[{"count":0,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/126\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/media?parent=126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/categories?post=126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/tags?post=126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}