{"id":1477,"date":"2009-03-11T22:44:55","date_gmt":"2009-03-11T20:44:55","guid":{"rendered":"http:\/\/www.urbinavolant.com\/verbavolant\/?p=1477"},"modified":"2010-08-10T10:01:57","modified_gmt":"2010-08-10T08:01:57","slug":"indigente-acera","status":"publish","type":"post","link":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2009\/03\/11\/indigente-acera\/","title":{"rendered":"Indigente. Acera Fragmentos #14"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/www.flickr.com\/photos\/libertinus\/410903364\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2009\/03\/alone.jpg\" class=\"aligncenter size-full wp-image-1478\" title=\"alone\" alt=\"alone\" width=\"500\" height=\"226\" srcset=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2009\/03\/alone.jpg 500w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2009\/03\/alone-300x135.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Es una mujer gorda. Apostada entre dos coches a las siete menos cuarto de la ma\u00f1ana. En una mano sujeta una botella de pl\u00e1stico con la que vierte unas gotas de agua al cepillo de dientes de la mano derecha. Se inclina despacio pero, a\u00fan as\u00ed, no puede evitar que el agua resbale por las comisuras de sus labios hasta colarse por el cuello. Luego se ha bajado la ropa interior. Se ha agachado y ha orinado con ruda presteza. Ha finalizado su ritual de aseo personal con chorros de agua enfocados a la cara, con indiscriminada generosidad hacia sus ojos, hacia su frente, hacia sus mofletes.<\/p>\n<p style=\"text-align: justify;\">La mujer se ha acercado al banco p\u00fablico de madera para recoger una manta, un saco de dormir y un pl\u00e1stico demasiado fino con el que intenta protegerse de la humedad. A veces tiene que dormir en el c\u00e9sped de un jard\u00edn. O en la hierba a orillas del r\u00edo. Ha doblado el saco de dormir con una perfecci\u00f3n que asusta, as\u00ed que ha podido deslizarlo hacia la funda con una facilidad no pronosticable de fijarnos solamente en sus manos, rechonchas y llenas de costrar extra\u00f1as. Sin despertador posible, todas las ma\u00f1anas se despereza a la misma hora, cuando el fr\u00edo acumulado a lo largo de la noche le hace levantarse. Cuando el miedo a las agresiones -todav\u00eda guarda una cicatriz de veinticuatro puntos en la espalda gracias a una paliza propinada por unos j\u00f3venes demasiado finos-. Cuando la verg\u00fcenza, que todav\u00eda no ha podido huir de su yo profundo le transmite la posibilidad de ser vista por mucha gente.<\/p>\n<p style=\"text-align: justify;\">La siguiente parada ser\u00e1 la estaci\u00f3n de autobuses. All\u00ed se calienta y contempla todo el trasiego de gente que marcha hacia sus destinos. C\u00f3modos y seguros. Antes alternaba estas estancias con la estaci\u00f3n de tren, pero ella vive en un territorio bien demarcado y conocido. Todo lo que pueda andar un cuerpo castigado con una inmensa mochila y una bolsa de deporte durante no m\u00e1s de veinte minutos. En los momentos de calma, se acerca al cuarto de ba\u00f1o para mirarse en el espejo. Todav\u00eda piensa qui\u00e9n co\u00f1o ser\u00e1 esa vieja que la mira de frente a ella, una mujer de treinta y cuatro a\u00f1os.<\/p>\n<p style=\"text-align: justify;\">Un poco m\u00e1s tarde, se repantinga en un largu\u00edsimo banco de piedra casi en el centro de la ciudad. El cruce r\u00e1pido de los coches, los viandantes que se dirigen hacia sus trabajos le hacen pensar lo despacio que marcha su vida. Un marido que le quit\u00f3 todo lo que ten\u00eda. Las duras bofetadas en un rostro que empez\u00f3 a cruzar las v\u00edas de la miseria y de la delincuencia menuda.<\/p>\n<p style=\"text-align: justify;\">Ahora ha dejado el alcohol y bebe cantidades ingentes de agua. Las limosnas que no pide alcanzan para el bocadillo, un poco de embutido, piezas de fruta casi podridas abandonadas en los contenedores del mercado. Los comerciantes, a veces, le dan alg\u00fan extra. Un lujo que le hace saborear todo lo que se pierde cada d\u00eda de su vida.<\/p>\n<p style=\"text-align: justify;\">A eso de las cuatro de la tarde, ha visto a un hombre de unos cuarenta a\u00f1os, embebido en sus catastr\u00f3fes, en sus obsesiones y cavilando sobre lo mal que funciona el mundo a cada instante. \u00abQu\u00e9 suerte tiene tu cuerpo. Hijoputa\u00bb, le ha dicho. Por la acento, el hombre ha sabido que era portuguesa. Ha mirado de refil\u00f3n y ha seguido su senda hacia ninguna parte.<\/p>\n<p style=\"text-align: justify;\">(Imagen de <a href=\"http:\/\/www.flickr.com\/photos\/libertinus\/410903364\/\" target=\"_blank\">Libertinus<\/a>)<\/p>\n<p>(Puedes ir leyendo la secuencia de\u00a0<em>Fragmentos para una teor\u00eda del caos<\/em> de forma ordenada pinchando\u00a0<a href=\"http:\/\/urbinavolant.com\/index.php\/2008\/11\/fragmentos-para-una-teoria-del-caos\/\" target=\"_blank\">aqu\u00ed<\/a>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es una mujer gorda. Apostada entre dos coches a las siete menos cuarto de la ma\u00f1ana. En una mano sujeta una botella de pl\u00e1stico con la que vierte unas gotas de agua al cepillo de dientes de la mano derecha. Se inclina despacio pero, a\u00fan as\u00ed, no puede evitar que el agua resbale por las &#8230; <a title=\"Indigente. Acera Fragmentos #14\" class=\"read-more\" href=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2009\/03\/11\/indigente-acera\/\" aria-label=\"Leer m\u00e1s sobre Indigente. Acera Fragmentos #14\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[117],"tags":[161],"class_list":["post-1477","post","type-post","status-publish","format-standard","hentry","category-fragmentos-para-una-teoria-del-caos","tag-fragmentos-para-una-teoria-del-caos"],"_links":{"self":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/1477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/comments?post=1477"}],"version-history":[{"count":0,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/1477\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/media?parent=1477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/categories?post=1477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/tags?post=1477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}