{"id":2140,"date":"2009-12-30T13:41:54","date_gmt":"2009-12-30T11:41:54","guid":{"rendered":"http:\/\/www.urbinavolant.com\/verbavolant\/?p=2140"},"modified":"2009-12-30T13:41:54","modified_gmt":"2009-12-30T11:41:54","slug":"la-suerte-la-lluvia-nuestros-suenos-encerrados","status":"publish","type":"post","link":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2009\/12\/30\/la-suerte-la-lluvia-nuestros-suenos-encerrados\/","title":{"rendered":"La suerte, la lluvia, nuestros sue\u00f1os encerrados"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/www.flickr.com\/photos\/haddhar\/457433116\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2009\/12\/espejo.jpg\" alt=\"Espejo\" class=\"aligncenter size-full wp-image-2141\" title=\"espejo\" alt=\"\" width=\"362\" height=\"500\" srcset=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2009\/12\/espejo.jpg 362w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2009\/12\/espejo-217x300.jpg 217w\" sizes=\"auto, (max-width: 362px) 100vw, 362px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Todos perdemos gatos negros que se cruzan en nuestro deambular urbano. Todas las min\u00fasculas porciones de sal vertidas en un mal trago de aderezo en la ensalada se desparraman por el mantel trocitos de angustia que ahora para por ser sabrosa. Las escaleras se empecinan por atravesar su tri\u00e1ngulo entre nuestro ser callejero, de la misma manera que los espejos rotos se han mostrado proclives a deshacerse en a\u00f1icos cuando nos vemos reflejados. Hay que contarle los botones de la camisa a todos los pelirrojos con los que nos tropecemos (y mira que son una especie en extinci\u00f3n). Tan somnolientos estamos en nuestro matutino despertar que no miramos siquiera con qu\u00e9 pie pisamos, aunque nuestras zapatillas se encuentren a a\u00f1os luz de nuestra cordura. La suerte es como la lluvia: siempre abrimos el paraguas cuando hace falta, aunque sea dentro de la mansi\u00f3n de nuestros sue\u00f1os.<\/p>\n<p style=\"text-align: justify;\">(Imagen de <a href=\"http:\/\/www.flickr.com\/photos\/haddhar\/457433116\/\" target=\"_blank\">Haddhar<\/a>.)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos perdemos gatos negros que se cruzan en nuestro deambular urbano. Todas las min\u00fasculas porciones de sal vertidas en un mal trago de aderezo en la ensalada se desparraman por el mantel trocitos de angustia que ahora para por ser sabrosa. Las escaleras se empecinan por atravesar su tri\u00e1ngulo entre nuestro ser callejero, de la &#8230; <a title=\"La suerte, la lluvia, nuestros sue\u00f1os encerrados\" class=\"read-more\" href=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2009\/12\/30\/la-suerte-la-lluvia-nuestros-suenos-encerrados\/\" aria-label=\"Leer m\u00e1s sobre La suerte, la lluvia, nuestros sue\u00f1os encerrados\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[72],"tags":[],"class_list":["post-2140","post","type-post","status-publish","format-standard","hentry","category-contrastes"],"_links":{"self":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/2140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/comments?post=2140"}],"version-history":[{"count":0,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/2140\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/media?parent=2140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/categories?post=2140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/tags?post=2140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}