{"id":3489,"date":"2011-07-17T16:25:51","date_gmt":"2011-07-17T15:25:51","guid":{"rendered":"http:\/\/www.urbinavolant.com\/verbavolant\/?p=3489"},"modified":"2011-07-17T16:25:51","modified_gmt":"2011-07-17T15:25:51","slug":"constelaciones-beneficios-y-danos","status":"publish","type":"post","link":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2011\/07\/17\/constelaciones-beneficios-y-danos\/","title":{"rendered":"Constelaciones, beneficios y da\u00f1os"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/www.flickr.com\/photos\/smb_flickr\/528713203\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3490\" src=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2011\/07\/528713203_9d7937f694_z.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2011\/07\/528713203_9d7937f694_z.jpg 640w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2011\/07\/528713203_9d7937f694_z-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">La <a href=\"http:\/\/es.wikipedia.org\/wiki\/Constelaciones_familiares\" target=\"_blank\">\u00abconstelaci\u00f3n familiar\u00bb<\/a> es una terapia creada \u2013y sin evidencia cient\u00edfica comprobada\u2013 por Bert Hellinger que tiene su fundamento en elementos culturales de procedencia inconsciente y que podr\u00eda considerarse una variante de algunas de las teor\u00edas del inconsciente colectivo de Carl Gustav Jung. Seg\u00fan este pensador alem\u00e1n, muchos problemas psicol\u00f3gicos esconden sus razones en conflictos, h\u00e1bitos y normas familiares registradas y asimiladas por un individuo y que influyen poderosa, aunque no de forma voluntaria, en su con(s)ciencia.<\/p>\n<p style=\"text-align: justify;\">M\u00e1s all\u00e1 de los elementos en los que se basa esta teor\u00eda como terapia, me ha parecido interesante la forma de estudiar la familia desde el punto de vista de<a href=\"http:\/\/es.wikipedia.org\/wiki\/Teor%C3%ADa_de_sistemas\" target=\"_blank\"> la teor\u00eda general de sistemas<\/a>. Me resulta muy curioso, por ejemplo, que algunos integrantes de estas constelaciones se unen con el objetivo de reducir el sentimiento de otro de los miembros y surgen implicaciones muy interesantes como la arrogaci\u00f3n, mediante la cual\u00a0algunos miembros se apropian del derecho o de la responsabilidad de otra persona del grupo en aras de un supuesto\u00a0equilibrio.<\/p>\n<p style=\"text-align: justify;\">Particularmente, al margen de los beneficios terap\u00e9uticos que pueda tener comprender este funcionamiento, a m\u00ed me interesa mucho m\u00e1s el comprobar el da\u00f1o que puede hacer, a su vez, tomar las relaciones como clanes y querer encajar con calzador a individuos procedentes de sistemas diferentes a un sistema tomado como el \u00fanico v\u00e1lido, incluso aunque se perjudique el equilibrio mismo del clan al que se pertenece. Por ejemplo, la t\u00e1ctica de <a href=\"http:\/\/depsicologia.com\/exclusion-del-sistema-familiar\/\" target=\"_blank\">exclusi\u00f3n del sistema<\/a>\u00a0es contradictoria en s\u00ed misma, ya que beneficia al sistema del clan originario, pero genera, a su vez, un sistema viciado en el que algunos individuos del mismo clan pueden salir perjudicados. Lo curioso del comportamiento humano es que hay muchas personas para las que ese sistema es tan poderoso que no son capaces de individualizarse y, por lo tanto, tener la autonom\u00eda suficiente para corregir los problemas. En definitiva, creo que la asunci\u00f3n de ese sistema de constelaciones puede ser positivo para la permanencia del clan en cuanto tal en su forma originaria, pero no es necesariamente el mejor para los individuos que lo integran. A veces se alcanzan mayores logros con la defensa de la individualidad que con la asunci\u00f3n del gregarismo, sobre todo cuando este conduce a la ignorancia del otro y a la negaci\u00f3n de los derechos de los que no pertenecen a la constelaci\u00f3n pero interact\u00faan con gente de su \u00f3rbita.<\/p>\n<p style=\"text-align: justify;\">Somos animales de costumbres y las costumbres crean culturas, pero tambi\u00e9n somos seres individualizados que debemos saber asumir muy bien los roles de nuestra actuaci\u00f3n para ir en beneficio del progreso, para no convertir las relaciones en reba\u00f1os. Solo as\u00ed brilla la humanidad de los individuos por encima de la dudosa luz de generalizaciones que, por serlo, cercenan la ra\u00edz misma que les da sentido.<\/p>\n<p style=\"text-align: justify;\">(Imagen de <a href=\"http:\/\/www.flickr.com\/photos\/smb_flickr\/528713203\/\" target=\"_blank\">SantiMB<\/a>.)<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La \u00abconstelaci\u00f3n familiar\u00bb es una terapia creada \u2013y sin evidencia cient\u00edfica comprobada\u2013 por Bert Hellinger que tiene su fundamento en elementos culturales de procedencia inconsciente y que podr\u00eda considerarse una variante de algunas de las teor\u00edas del inconsciente colectivo de Carl Gustav Jung. Seg\u00fan este pensador alem\u00e1n, muchos problemas psicol\u00f3gicos esconden sus razones en conflictos, &#8230; <a title=\"Constelaciones, beneficios y da\u00f1os\" class=\"read-more\" href=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2011\/07\/17\/constelaciones-beneficios-y-danos\/\" aria-label=\"Leer m\u00e1s sobre Constelaciones, beneficios y da\u00f1os\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[72],"tags":[],"class_list":["post-3489","post","type-post","status-publish","format-standard","hentry","category-contrastes"],"_links":{"self":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/3489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/comments?post=3489"}],"version-history":[{"count":0,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/3489\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/media?parent=3489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/categories?post=3489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/tags?post=3489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}