{"id":416,"date":"2008-05-15T18:21:21","date_gmt":"2008-05-15T18:21:21","guid":{"rendered":"http:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2008\/05\/15\/soy-modestia-aparte-un-hombre-objeto\/"},"modified":"2008-05-15T19:56:10","modified_gmt":"2008-05-15T19:56:10","slug":"soy-modestia-aparte-un-hombre-objeto","status":"publish","type":"post","link":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2008\/05\/15\/soy-modestia-aparte-un-hombre-objeto\/","title":{"rendered":"Soy, modestia aparte, un hombre objeto"},"content":{"rendered":"<p align=\"center\"><a href=\"http:\/\/www.flickr.com\/photos\/urbinavolant\/2476835860\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2008\/05\/complu.jpg\" title=\"Complu\" alt=\"Complu\" height=\"333\" width=\"500\" \/><\/a><\/p>\n<p style=\"text-align: justify\">Pospongo para las pr\u00f3ximas entradas <a href=\"http:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2008\/05\/14\/nuestro-descubrimiento\/\" target=\"_blank\" title=\"Nuestro descubrimiento, en Verbavolant\">mi proyecto<\/a> de hablar del interior y del exterior, porque un suceso imprevisto ha cambiado mi vida. Me he dado cuenta de que <strong><span style=\"font-size: 11pt; line-height: 115%; font-family: 'Calibri','sans-serif'; color: #948a54\">soy un hombre objeto<\/span><\/strong>. As\u00ed, sin comerlo ni beberlo, sin salir a buscarlo y con toda la modestia del mundo. Las cosas son as\u00ed, amigos. Y lo he descubierto en el transcurso natural del d\u00eda a d\u00eda, leyendo. Si desciendo, evidencia a evidencia, me doy cuenta de que soy un ser humano y, por lo tanto, animal; animal y, por lo tanto, ser vivo; ser vivo y, por lo tanto, cosa, objeto. Me desmarco, pues, de las hienas, de los champi\u00f1ones y de las abstracciones punto por punto y evolutivamente. Como dice <a href=\"http:\/\/www.mosterin.com\/\" target=\"_blank\">Jes\u00fas Moster\u00edn<\/a>, \u00abdecir de algo o de alguien que es una cosa, lejos de ser un insulto, es un piropo ontol\u00f3gico. La alternativa a ser una cosa es ser un mero accidente, o una abstracci\u00f3n, o una ficci\u00f3n\u00bb (<em>La naturaleza humana<\/em>, Espasa-Calpe, 2007, p\u00e1g. 54). Y no os pod\u00e9is imaginar lo que me alegro de no ser una hiena (aunque sea un animal no carente de encanto y equivalente a unos cuantos humanos que conozco), de eludir el champi\u00f1\u00f3n (aunque sea la exquisitez de las basuras, pero inevitablemente unido a la cocci\u00f3n junto con el insulso perejil) o de ser una abstracci\u00f3n (que se pierde en el ser no siendo nada). Eso, ser una cosa, es algo que yo nos lo dec\u00eda Arist\u00f3teles con palabras m\u00e1s rimbombantes (<em>sustancia<\/em>, dicen los latinos y los traductores; <em>ous\u00eda<\/em>, dec\u00eda \u00e9l). Pero cosa est\u00e1 bien. Me gusta.<\/p>\n<p style=\"text-align: justify\">Ahora me miro al <a href=\"http:\/\/www.urbinavolant.com\/verbavolant\/?s=espejos\" target=\"_blank\" title=\"Los espejos en Verba volant\">espejo<\/a> (\u00a1<a href=\"http:\/\/www.seriezeta.com\/k\/category\/fotografik\/autorretretes\/\" target=\"_blank\">Sr. K<\/a>, me gustas un huevo!) y, vi\u00e9ndome cosa, recupero mi <a href=\"http:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2007\/11\/03\/30\/\" target=\"_blank\" title=\"La dignidad socr\u00e1tica\">dignidad<\/a>. Me aprecio, me acerco y dejo de ver arrugas, canas, para contemplar laberintos, surcos de belleza enmarcada. Y me siento digno <em>parternaire <\/em>de las chicas de <a href=\"http:\/\/www.intimissimi.it\/english\/index.htm\" target=\"_blank\">Intimissimi <\/a>y de todo lo que se lleve por delante. Soy una cosa, amigos. Y s\u00f3lo falta que una <a href=\"http:\/\/es.wikipedia.org\/wiki\/Femme_fatale\" target=\"_blank\">femme fatale<\/a>  (<a href=\"http:\/\/www.laetitiacasta.com\/\" target=\"_blank\" title=\"Laetitia casta\">esta<\/a>, por ejemplo) venga, se arroje a mis brazos y me diga: \u00abVen aqu\u00ed, cosita m\u00eda\u00bb y as\u00ed quedar plenamente reconciliado con el mundo y con sus mol\u00e9culas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pospongo para las pr\u00f3ximas entradas mi proyecto de hablar del interior y del exterior, porque un suceso imprevisto ha cambiado mi vida. Me he dado cuenta de que soy un hombre objeto. As\u00ed, sin comerlo ni beberlo, sin salir a buscarlo y con toda la modestia del mundo. Las cosas son as\u00ed, amigos. Y lo &#8230; <a title=\"Soy, modestia aparte, un hombre objeto\" class=\"read-more\" href=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2008\/05\/15\/soy-modestia-aparte-un-hombre-objeto\/\" aria-label=\"Leer m\u00e1s sobre Soy, modestia aparte, un hombre objeto\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[44,46,73,26,25],"tags":[],"class_list":["post-416","post","type-post","status-publish","format-standard","hentry","category-comparaciones","category-espejo","category-evolucion","category-ficcion","category-realidad"],"_links":{"self":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/comments?post=416"}],"version-history":[{"count":0,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/416\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/media?parent=416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/categories?post=416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/tags?post=416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}