{"id":524,"date":"2008-07-17T10:00:37","date_gmt":"2008-07-17T10:00:37","guid":{"rendered":"http:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2008\/07\/17\/por-que-escribimos-historias\/"},"modified":"2008-07-17T10:00:37","modified_gmt":"2008-07-17T10:00:37","slug":"por-que-escribimos-historias","status":"publish","type":"post","link":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2008\/07\/17\/por-que-escribimos-historias\/","title":{"rendered":"Por qu\u00e9 escribimos historias"},"content":{"rendered":"<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2008\/07\/wordle-k.jpg\" width=\"640\" height=\"419\" title=\"Wordle K\" alt=\"Wordle K\" \/><\/p>\n<p style=\"text-align: justify\"><a href=\"http:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2008\/07\/15\/nubes-de-palabras\/\" target=\"_blank\" title=\"Nubes de palabras, en Verba volant\">Dec\u00edamos<\/a> que las palabras forman nubes. La lectura es nuestra manera de acumular palabras y experiencias en esas nubes que, henchidas de t\u00e9rminos, acaban por pesar tanto en nuestra cabeza como para que un d\u00eda decidamos que se derramen por nuestras manos hacia la pluma, hacia el l\u00e1piz o hacia el teclado. Se transforman, entonces, en formaciones nebulosas dirigidas hacia el papel o hacia la pantalla. Surgidas de nuestro universo, de nuestros miedos, de nuestras alegr\u00edas, de nuestras emociones. Con todos los defectos y virtudes de haberlas bebido, deglutido y expulsado. Con el inmenso placer -te\u00f1ido de verg\u00fcenza- de que sean compartidas con otros. Con la ilusi\u00f3n de pulsar la <em>a<\/em>, la <em>m<\/em>, la <em>o <\/em>y la <em>r <\/em>y que alguien adivine que hablamos de sentimientos y con la intenci\u00f3n e pulsar la <em>o<\/em>, la <em>d<\/em>, la <em>i <\/em>y la <em>o <\/em>y que alguien piense que hablamos desde la frustraci\u00f3n y del rencor. Con la ingenuidad de que las crean nuestras y exclusivas, o con la excesiva condescendencia de pensar que son prestadas y totalmente ajenas. Recibimos las palabras para ordenarlas en un nuevo caos. Contamos las mismas historias de siempre con nuevos medios para convertir los mismos argumentos en la piel de nuestro relato. Con la impotencia de no ser Shakespeare y con la altivez de pensar que somos diferentes. Con la debida cautela y el factor de protecci\u00f3n necesario y con la temeridad de estar demasiado expuestos al sol, que cuartea el cutis de nuestras frases. Contamos las historias de nuestra soledad para no sentirnos solos. Y contamos las historias de nuestra felicidad para crear ficciones. La ficci\u00f3n de que los dem\u00e1s crean que somos felices.<\/p>\n<p style=\"text-align: right\" align=\"right\"><span style=\"font-size: 10pt\">(La imagen procede de la libertad que me he tomado de hacer con <a href=\"http:\/\/wordle.net\/\" title=\"Wordle\"><em>Wordle<\/em><\/a> la nube de palabras del <a href=\"http:\/\/www.seriezeta.com\/k\/\" target=\"_blank\" title=\"Sr. K.\">Sr. K<\/a>, ejemplo de c\u00f3mo se escriben historias) <o:p><\/o:p><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dec\u00edamos que las palabras forman nubes. La lectura es nuestra manera de acumular palabras y experiencias en esas nubes que, henchidas de t\u00e9rminos, acaban por pesar tanto en nuestra cabeza como para que un d\u00eda decidamos que se derramen por nuestras manos hacia la pluma, hacia el l\u00e1piz o hacia el teclado. Se transforman, entonces, &#8230; <a title=\"Por qu\u00e9 escribimos historias\" class=\"read-more\" href=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2008\/07\/17\/por-que-escribimos-historias\/\" aria-label=\"Leer m\u00e1s sobre Por qu\u00e9 escribimos historias\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[61,13,85,65,104],"tags":[],"class_list":["post-524","post","type-post","status-publish","format-standard","hentry","category-laberintos","category-libros","category-literatura","category-sentido","category-silencio"],"_links":{"self":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/comments?post=524"}],"version-history":[{"count":0,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/524\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/media?parent=524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/categories?post=524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/tags?post=524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}