{"id":6131,"date":"2016-05-08T10:45:05","date_gmt":"2016-05-08T09:45:05","guid":{"rendered":"http:\/\/www.urbinavolant.com\/verbavolant\/?p=6131"},"modified":"2016-05-08T10:45:05","modified_gmt":"2016-05-08T09:45:05","slug":"menos-la-lluvia-de-cicatrices-sin-dolor","status":"publish","type":"post","link":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2016\/05\/08\/menos-la-lluvia-de-cicatrices-sin-dolor\/","title":{"rendered":"Menos la lluvia de cicatrices sin dolor"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/flic.kr\/p\/ecwLbg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6132\" src=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2016\/05\/8663121411_ed8b283517_z.jpg\" alt=\"Everyone wants to be happy\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2016\/05\/8663121411_ed8b283517_z.jpg 640w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2016\/05\/8663121411_ed8b283517_z-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>Antes de que te des cuenta, puedes acabar con demasiado fr\u00edo en el coraz\u00f3n. Por eso, digan lo que te digan, contin\u00faa. No importa que crean que est\u00e1s loco: nadie salvo t\u00fa sabe la verdad. Es dif\u00edcil escuchar las grandes palabras cuando, a tu alrededor, todos hablan tan alto, pero la meta es evitar la ca\u00edda y, para ello, la mejor medicina es la fiebre que acompa\u00f1a a tu abrazo. Todo se escurre entre nuestros dedos, menos la lluvia de cicatrices sin dolor.<\/p>\n<p>(<a href=\"http:\/\/www.urbinavolant.com\/verbavolant\/index.php\/tag\/canciones-prosificadas\/\" target=\"_blank\">Canci\u00f3n prosificada<\/a>, traducida\u00a0y modificada a voluntad de\u00a0<a class=\"fancybox-youtube\" href=\"https:\/\/youtu.be\/Vzo-EL_62fQ\" target=\"_blank\">\u201cBleeding Love\u201d<\/a>\u00a0de Leona Lewis,\u00a0con imagen de <a href=\"https:\/\/flic.kr\/p\/ecwLbg\">Nick Kenrick<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antes de que te des cuenta, puedes acabar con demasiado fr\u00edo en el coraz\u00f3n. Por eso, digan lo que te digan, contin\u00faa. No importa que crean que est\u00e1s loco: nadie salvo t\u00fa sabe la verdad. Es dif\u00edcil escuchar las grandes palabras cuando, a tu alrededor, todos hablan tan alto, pero la meta es evitar la &#8230; <a title=\"Menos la lluvia de cicatrices sin dolor\" class=\"read-more\" href=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2016\/05\/08\/menos-la-lluvia-de-cicatrices-sin-dolor\/\" aria-label=\"Leer m\u00e1s sobre Menos la lluvia de cicatrices sin dolor\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[57],"tags":[147],"class_list":["post-6131","post","type-post","status-publish","format-standard","hentry","category-musica","tag-canciones-prosificadas"],"_links":{"self":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/6131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/comments?post=6131"}],"version-history":[{"count":0,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/6131\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/media?parent=6131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/categories?post=6131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/tags?post=6131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}