{"id":638,"date":"2008-09-06T19:49:40","date_gmt":"2008-09-06T17:49:40","guid":{"rendered":"http:\/\/www.urbinavolant.com\/verbavolant\/?p=638"},"modified":"2008-09-06T19:49:40","modified_gmt":"2008-09-06T17:49:40","slug":"exprimir-un-retazo-de-vida-con-urgencia","status":"publish","type":"post","link":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2008\/09\/06\/exprimir-un-retazo-de-vida-con-urgencia\/","title":{"rendered":"Exprimir un retazo de vida (con urgencia)"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/flickr.com\/photos\/urbinavolant\/2832712236\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2008\/09\/exprimir.jpg\" class=\"aligncenter size-full wp-image-637\" title=\"Exprimiendo\" alt=\"Exprimir\" width=\"500\" height=\"303\" srcset=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2008\/09\/exprimir.jpg 500w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2008\/09\/exprimir-300x181.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Esta ma\u00f1ana me he levantado temprano pare exprimir ideas, pero no he sido capaz de sacar ninguna cosa brillante de la mollera. He pensado que no es posible exprimir los sesos sin tenerlos despiertos y alimentados, as\u00ed que he subido las persianas hasta ese l\u00edmite en el que se encasquillan, he abierto las ventanas de par en par, he insuflado todo el aire que he podido en mis pulmones hasta el punto de atragantarme -por avaricioso- y he empezado con el ritual del desayuno. Este ha sido el aut\u00e9ntico comienzo: abro el frigor\u00edfico y s\u00f3lo queda una naranja en el <a title=\"Habit\u00e1culo, en la RAE\" href=\"http:\/\/buscon.rae.es\/draeI\/SrvltGUIBusUsual?TIPO_HTML=2&amp;TIPO_BUS=3&amp;LEMA=habit%C3%A1culo\" target=\"_blank\">habit\u00e1culo<\/a> donde pernoctan frutas y verduras. Maldigo mi mala suerte: las naranjas de zumo s\u00f3lo se exprimen en la unidad cuando son bien compartidas. En casos como el m\u00edo, la naranja necesita compa\u00f1\u00eda. Disecciono con precisi\u00f3n y aprieto con ganas. Exprimida la naranja, soy incapaz de exprimir el cerebro sin exprimir el coraz\u00f3n. Intento apretarlo para sonsacarle toda la soledad que lleva dentro. Parece que se anima. Ahora, pertrechado ya de vitaminas, oligoelementos y palpitaciones vigorosas, paso a intentar exprimir lo que es mi vida.\u00a0 Y no lo logro. Dejo pasar m\u00e1s de doce horas desde el primer intento. Hasta ahora, que me he dado cuenta de que estaba pensando <a title=\"exprimer\" href=\"http:\/\/www.elpais.com\/diccionarios\/frances-espanol\/exprimer\" target=\"_blank\">en franc\u00e9s<\/a>, recordando tiempos m\u00e1s felices. Y percibo que <em>exprimir <\/em>ideas no es lo mismo que <em>expresarlas<\/em>, del mismo modo que no se puede ignorar que expresar es algo que puede confundirse con la <a title=\"express\" href=\"http:\/\/www.elpais.com\/diccionarios\/ingles-espanol\/express\" target=\"_blank\">urgencia<\/a> que uno tiene para decir y ser o\u00eddo -y escuchado-. Pero con las ideas siempre pasa como en el zumo: las gotas m\u00e1s apetitosas se quedan dentro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta ma\u00f1ana me he levantado temprano pare exprimir ideas, pero no he sido capaz de sacar ninguna cosa brillante de la mollera. He pensado que no es posible exprimir los sesos sin tenerlos despiertos y alimentados, as\u00ed que he subido las persianas hasta ese l\u00edmite en el que se encasquillan, he abierto las ventanas de &#8230; <a title=\"Exprimir un retazo de vida (con urgencia)\" class=\"read-more\" href=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2008\/09\/06\/exprimir-un-retazo-de-vida-con-urgencia\/\" aria-label=\"Leer m\u00e1s sobre Exprimir un retazo de vida (con urgencia)\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[44,72,61,5],"tags":[],"class_list":["post-638","post","type-post","status-publish","format-standard","hentry","category-comparaciones","category-contrastes","category-laberintos","category-soledad"],"_links":{"self":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/comments?post=638"}],"version-history":[{"count":0,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/638\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/media?parent=638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/categories?post=638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/tags?post=638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}