{"id":6491,"date":"2018-01-06T20:07:15","date_gmt":"2018-01-06T19:07:15","guid":{"rendered":"http:\/\/www.urbinavolant.com\/verbavolant\/?p=6491"},"modified":"2018-01-06T20:07:15","modified_gmt":"2018-01-06T19:07:15","slug":"transparencia-y-desaparicion","status":"publish","type":"post","link":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2018\/01\/06\/transparencia-y-desaparicion\/","title":{"rendered":"Transparencia y desaparici\u00f3n"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/flic.kr\/p\/Ttw9h1\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6492\" src=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2018\/01\/33785621760_d4f8e18f7b_z.jpg\" alt=\"\" width=\"640\" height=\"424\" srcset=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2018\/01\/33785621760_d4f8e18f7b_z.jpg 640w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2018\/01\/33785621760_d4f8e18f7b_z-300x199.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\u00abLa transparencia, Dios, la transparencia\u00bb, dec\u00eda Juan Ram\u00f3n hablando de su lucha hermosa con lo divino. Despu\u00e9s de haber probado todos los moldes, necesitamos librarnos de las constricciones. Nos vanagloriamos primero de ser opacos, luego ansiamos que la luz pase sin desvelarnos. Pero llega un momento en que nos hace falta convertirnos en un cristal disimulado, que permita transmitir la luz, que es mucho m\u00e1s importante que nosotros. \u00bfEn qu\u00e9 queda nuestra existencia? En un filtro que module algunos rayos, pero nada m\u00e1s. \u00bfSe puede confiar, a\u00fan, en nuestra necesidad? \u00bfNo es excesiva nuestra (sobre)exposici\u00f3n? \u00bfTan interesantes son los fragmentos de una vida reconstruida como Frankenstein en la visita del cirujano pl\u00e1stico?<\/p>\n<p style=\"text-align: justify;\">Y la desaparici\u00f3n. No definitiva, no lo s\u00e9. No un derrumbe, sino una goma de borrar pautada por la paciencia. Dejando que las frases revoloteen por la cabeza y all\u00ed se queden. Ser menos sin aparentar m\u00e1s. Un desvanecimiento simp\u00e1tico, un gozo fundido en negro, un horizonte que quita para poner. Un silencio relativo, matizado. Y una implosi\u00f3n que ojal\u00e1 revierta \u2013alg\u00fan d\u00eda\u2013 en algo m\u00e1s grande.<\/p>\n<p>Imagen de <a href=\"https:\/\/flic.kr\/p\/Ttw9h1\">Tobi Gaulke<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLa transparencia, Dios, la transparencia\u00bb, dec\u00eda Juan Ram\u00f3n hablando de su lucha hermosa con lo divino. Despu\u00e9s de haber probado todos los moldes, necesitamos librarnos de las constricciones. Nos vanagloriamos primero de ser opacos, luego ansiamos que la luz pase sin desvelarnos. Pero llega un momento en que nos hace falta convertirnos en un cristal &#8230; <a title=\"Transparencia y desaparici\u00f3n\" class=\"read-more\" href=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2018\/01\/06\/transparencia-y-desaparicion\/\" aria-label=\"Leer m\u00e1s sobre Transparencia y desaparici\u00f3n\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[65],"tags":[],"class_list":["post-6491","post","type-post","status-publish","format-standard","hentry","category-sentido"],"_links":{"self":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/6491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/comments?post=6491"}],"version-history":[{"count":0,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/6491\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/media?parent=6491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/categories?post=6491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/tags?post=6491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}