{"id":7369,"date":"2020-03-19T20:41:11","date_gmt":"2020-03-19T19:41:11","guid":{"rendered":"https:\/\/www.urbinavolant.com\/verbavolant\/?p=7369"},"modified":"2020-03-19T20:41:20","modified_gmt":"2020-03-19T19:41:20","slug":"viaje-alrededor-de-mi-casa-2","status":"publish","type":"post","link":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2020\/03\/19\/viaje-alrededor-de-mi-casa-2\/","title":{"rendered":"Viaje alrededor de mi casa #2"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1370\" height=\"2560\" src=\"https:\/\/i1.wp.com\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/03\/IMG_0094-scaled.jpg?fit=548%2C1024&amp;ssl=1\" alt=\"\" class=\"wp-image-7370\" srcset=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/03\/IMG_0094-scaled.jpg 1370w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/03\/IMG_0094-161x300.jpg 161w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/03\/IMG_0094-548x1024.jpg 548w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/03\/IMG_0094-768x1435.jpg 768w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/03\/IMG_0094-822x1536.jpg 822w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/03\/IMG_0094-1096x2048.jpg 1096w\" sizes=\"auto, (max-width: 1370px) 100vw, 1370px\" \/><\/figure><\/div>\n\n\n\n<p style=\"font-size:17px\">Hoy he podido escapar. He respirado hondo, he abierto a machetazos brozas y brozas de vegetaci\u00f3n y, detr\u00e1s, he encontrado una puerta. Estaba cerrada con llave, maldita sea. Me he acordado de un mensaje que recib\u00ed hace tiempo, cuando ten\u00eda tel\u00e9fono m\u00f3vil antes de quedarme en la indigencia tecnol\u00f3gica. \u00abLas vasijas no sirven solo para guardar el vino\u00bb. Record\u00e9 eso, que hace unos meses, en unos enseres encontrados junto a mi recibidor (un amigo pedante lo llamar\u00eda <em>hall<\/em>), hab\u00eda un cuenco de barro en el que alguien hab\u00eda realizado unos dibujos geom\u00e9tricos parecidos a cruces gamadas. All\u00ed hab\u00eda una llave solitaria, que nunca supe para que serv\u00eda.<\/p>\n\n\n\n<p style=\"font-size:17px\">Di media vuelta, recorr\u00ed de nuevo todo el camino. Me llev\u00f3 casi medio d\u00eda regresar con el preciado trofeo en la mano. Gir\u00e9 la cerradura, que parec\u00eda casi inutilizada. Pero insist\u00ed, puse toda mi fuerza en el giro y se escuch\u00f3 la m\u00fasica m\u00e1gica que hace \u00abclic\u00bb y con la que comienza todo.<\/p>\n\n\n\n<p style=\"font-size:17px\">Me hab\u00eda puesto ropa c\u00f3moda para la excursi\u00f3n. El pantal\u00f3n corto y la camiseta sin mangas me provocaron muchas rozaduras y heridas, pero no me importo. Me esperaba una monta\u00f1a escalonada. Era muy corta, pero suficiente.<\/p>\n\n\n\n<p style=\"font-size:17px\">Comenc\u00e9 el ascenso y, demasiado pronto, llegu\u00e9 a la cima, tras la que una niebla persistente me imped\u00eda ver m\u00e1s all\u00e1. Cansado de no cansarme, volv\u00ed a bajar por la ladera y, a partir de entonces, fui emprendiendo subidas y bajadas de las maneras m\u00e1s estramb\u00f3ticas. Saltando con dos pies, haciendo sentadillas, alargando cada pie con pasos ascendentes y largos, a pasitos cortos y veloces. Lo que al principio era pura rutina, al cabo de poco tiempo, me hizo sudar. La niebla se fue atemperando y empec\u00e9 a ver una luz parecida a esas que un alcalde de cierta ciudad rec\u00f3ndita en el noroeste llamaba \u00ableds\u00bb, pero no eran millones. Eran cuatro.<\/p>\n\n\n\n<p style=\"font-size:17px\">Despu\u00e9s de llegar y llegar y llegar y llegar, vi que no avanzaba. Estuve a punto de lanzarme al precipicio, como intent\u00f3 una vez Robinson Crusoe, pero un exceso de prudencia me hizo volver. La puerta estaba entornada. Cog\u00ed la llave que hab\u00eda dejado en el bolsillo interior del pantal\u00f3n corto. Y me volv\u00ed a encerrar, como si fuera estuviese un enemigo al que no supe identificar. Todav\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy he podido escapar. He respirado hondo, he abierto a machetazos brozas y brozas de vegetaci\u00f3n y, detr\u00e1s, he encontrado una puerta. Estaba cerrada con llave, maldita sea. Me he acordado de un mensaje que recib\u00ed hace tiempo, cuando ten\u00eda tel\u00e9fono m\u00f3vil antes de quedarme en la indigencia tecnol\u00f3gica. \u00abLas vasijas no sirven solo para &#8230; <a title=\"Viaje alrededor de mi casa #2\" class=\"read-more\" href=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2020\/03\/19\/viaje-alrededor-de-mi-casa-2\/\" aria-label=\"Leer m\u00e1s sobre Viaje alrededor de mi casa #2\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[61,65,63],"tags":[171],"class_list":["post-7369","post","type-post","status-publish","format-standard","hentry","category-laberintos","category-sentido","category-viajes","tag-viaje-alrededor-de-mi-casa"],"_links":{"self":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/7369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/comments?post=7369"}],"version-history":[{"count":0,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/7369\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/media?parent=7369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/categories?post=7369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/tags?post=7369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}