{"id":7414,"date":"2020-04-26T18:38:22","date_gmt":"2020-04-26T17:38:22","guid":{"rendered":"https:\/\/www.urbinavolant.com\/verbavolant\/?p=7414"},"modified":"2020-04-26T18:38:25","modified_gmt":"2020-04-26T17:38:25","slug":"no-sabes-no-estas-no-eres","status":"publish","type":"post","link":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2020\/04\/26\/no-sabes-no-estas-no-eres\/","title":{"rendered":"No sabes, no est\u00e1s, no eres"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/flic.kr\/p\/5zccke\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/04\/3001055791_c85b23b1d9_c.jpg\" alt=\"\" class=\"wp-image-7415\" width=\"600\" height=\"480\" srcset=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/04\/3001055791_c85b23b1d9_c.jpg 800w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/04\/3001055791_c85b23b1d9_c-300x240.jpg 300w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/04\/3001055791_c85b23b1d9_c-768x614.jpg 768w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/div>\n\n\n\n<p style=\"font-size:17px\">No est\u00e1s seguro, no sabes si est\u00e1s bien o mal o regular. Si echas de menos la calle o est\u00e1s a gusto en casa. Si te gustar\u00eda tener m\u00e1s tiempo para ti o no disponer de un minuto, que las tareas te acogotasen el cerebro o que las ideas se desplazasen sin moverse, planas, en todo el sentido de la inercia. <\/p>\n\n\n\n<p style=\"font-size:17px\">No est\u00e1s seguro de c\u00f3mo est\u00e1 el mundo por fuera. Si es apolipsis o colapso, si es centro o periferia, si se acomoda a la norma al descontrol. No conoces remedios infalibles ni para la pol\u00edtica ni para la ciencia ni para el bienestar interior. Ni eres consciente de si tu cuerpo es una s\u00edncopa o un ap\u00f3cope. <\/p>\n\n\n\n<p style=\"font-size:17px\">No tienes muy claro qu\u00e9 canci\u00f3n escoger, que pel\u00edcula elegir, qu\u00e9 libro dejar a medias y cu\u00e1l exprimir hasta las ultimas consecuencias. No sabes a qui\u00e9n llamar, a qui\u00e9n acudir, ni siquiera est\u00e1s muy seguro si quieres contemplar qu\u00e9 es lo que les ocurre a otros o permanecer en la m\u00e1s ignominiosa de las ignorancias.<\/p>\n\n\n\n<p style=\"font-size:17px\">No sabes si vas o vienes, aunque sabes que no vas a ning\u00fan lado ni vienes de ning\u00fan sitio. Tampoco sabes si ir\u00e1s o vendr\u00e1s. Ni hac\u00eda d\u00f3nde, ni c\u00f3mo. Cu\u00e1ndo no depende de ti.<\/p>\n\n\n\n<p style=\"font-size:17px\">Y as\u00ed pasan d\u00edas y d\u00edas y d\u00edas. Y t\u00fa no est\u00e1s ni eres. Ni te manifiestas.<\/p>\n\n\n\n<p>Imagen de <a href=\"https:\/\/flic.kr\/p\/5zccke\" target=\"_blank\" aria-label=\"Bart (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"aioseop-link\">Bart<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No est\u00e1s seguro, no sabes si est\u00e1s bien o mal o regular. Si echas de menos la calle o est\u00e1s a gusto en casa. Si te gustar\u00eda tener m\u00e1s tiempo para ti o no disponer de un minuto, que las tareas te acogotasen el cerebro o que las ideas se desplazasen sin moverse, planas, en &#8230; <a title=\"No sabes, no est\u00e1s, no eres\" class=\"read-more\" href=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2020\/04\/26\/no-sabes-no-estas-no-eres\/\" aria-label=\"Leer m\u00e1s sobre No sabes, no est\u00e1s, no eres\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[37,61],"tags":[],"class_list":["post-7414","post","type-post","status-publish","format-standard","hentry","category-abismo","category-laberintos"],"_links":{"self":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/7414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/comments?post=7414"}],"version-history":[{"count":0,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/7414\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/media?parent=7414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/categories?post=7414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/tags?post=7414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}