{"id":7467,"date":"2020-10-05T10:13:11","date_gmt":"2020-10-05T09:13:11","guid":{"rendered":"https:\/\/www.urbinavolant.com\/verbavolant\/?p=7467"},"modified":"2020-10-05T10:13:17","modified_gmt":"2020-10-05T09:13:17","slug":"compartir-a-mafalda","status":"publish","type":"post","link":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2020\/10\/05\/compartir-a-mafalda\/","title":{"rendered":"Compartir a Mafalda"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/10\/Captura-de-pantalla-2020-10-05-a-las-10.44.10.png\" alt=\"\" class=\"wp-image-7469\" width=\"407\" height=\"311\" srcset=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/10\/Captura-de-pantalla-2020-10-05-a-las-10.44.10.png 542w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/10\/Captura-de-pantalla-2020-10-05-a-las-10.44.10-300x230.png 300w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/figure><\/div>\n\n\n\n<p style=\"font-size:17px\"><a href=\"https:\/\/elpais.com\/cultura\/2020-09-30\/fallece-quino-creador-de-mafalda-y-el-dibujante-mas-internacional-del-idioma-espanol.html\" target=\"_blank\" rel=\"noreferrer noopener\">Muri\u00f3 Quino hace unos d\u00edas<\/a> y todas las redes se convirtieron en un emotivo escaparate de homenajes a ese gran dibujante, humorista y fil\u00f3sofo de las verdades cotidianas m\u00e1s profundas. Cada contribuci\u00f3n subrayaba la manera que hab\u00eda tenido Quino (con su genial Mafalda como exponente m\u00e1ximo) de acompa\u00f1ar nuestras vidas, la manera de expresar de manera acertad\u00edsima sobre todo lo que nos pasa, sobre c\u00f3mo somos, sobre todo lo que les ocurre y la manera de ser de todos los que tenemos alrededor. En pocas palabras, Quino ha sabido explicar el mundo y nuestro mundo.<\/p>\n\n\n\n<p style=\"font-size:17px\">Por supuesto, estas muestras de justa veneraci\u00f3n ven\u00edan acompa\u00f1adas con tiras c\u00f3micas como ejemplo de ese ajuste entre su pensamiento y nuestra manera de pensar. Con una argumentaci\u00f3n sencillamente complicada, es inevitable sonre\u00edr y sentir que formamos parte de algo com\u00fan.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"228\" src=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/10\/NEROFH2.jpg\" alt=\"\" class=\"wp-image-7468\" srcset=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/10\/NEROFH2.jpg 800w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/10\/NEROFH2-300x86.jpg 300w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/10\/NEROFH2-768x219.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p style=\"font-size:17px\">Todas esas contribuciones, como digo, nacen del cari\u00f1o \u2014tambi\u00e9n, reconozc\u00e1moslo, ha habido lugar para el postrero\u2014 y son indicio de esa chispa y esa sinton\u00eda. No obstante, a trav\u00e9s de mensajes de WhatsApp, han empezado a proliferar (yo he recibido varios) enlaces al libro <em>Todo Mafalda<\/em> en PDF. Creo que ese \u00abdetalle\u00bb no supone ning\u00fan signo de amor por Quino ni representa nada de la esencia del humorista. Regalar <em>totalmente<\/em> a Mafalda no solo es algo reprobable (es un libro que sigue en venta y, por lo tanto, se regatea a los herederos de Quino una ganancia que les pertenece), sino que es algo carente de sentido. Si compartir detalles de c\u00f3mo contribuye Mafalda a nuestro mundo es magn\u00edfico, compartir una integridad amorfa es feo, invasivo y de mal gusto. Es algo as\u00ed como regalar una colonia costos\u00edsima en una garrafa de diez litros.<\/p>\n\n\n\n<p style=\"font-size:17px\">Los que aman a Mafalda conservan como oro en pa\u00f1o esos preciosos libros apasaidos. Los que llegaron m\u00e1s tarde o quer\u00edan conservar todo ese legado, compraron el libro que reun\u00eda todo lo anterior, que es lo que corresponde. Realizar ese esfuerzo para tener ese magn\u00edfico repositorio de pensamiento expresado en clave de humor. Yo todav\u00eda recuerdo con cari\u00f1o especial el momento en el que compr\u00e9 el libro en la librer\u00eda Ateneo en Buenos Aires.<\/p>\n\n\n\n<p style=\"font-size:17px\">Como he trabajado mucho con Mafalda (es un fil\u00f3n parra muchos aspectos relacionados con la comunicaci\u00f3n y con el lenguaje), tambi\u00e9n tengo ese famoso PDF y nunca lo he compartido con nadie: jam\u00e1s se me ocurr\u00eda desparramarlo a los cuatro vientos. Cuando se trata de Quino, destapemos unas gotas de genialidad. Para percibir su esencia y todo lo que le debemos.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"736\" height=\"228\" src=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/10\/felipe-deberes-quino.jpg\" alt=\"\" class=\"wp-image-7470\" srcset=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/10\/felipe-deberes-quino.jpg 736w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2020\/10\/felipe-deberes-quino-300x93.jpg 300w\" sizes=\"auto, (max-width: 736px) 100vw, 736px\" \/><\/figure><\/div>\n\n\n\n<p style=\"font-size:17px\">A m\u00ed, que me gustar\u00eda ser Mafalda, siempre me he quedado en Felipe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muri\u00f3 Quino hace unos d\u00edas y todas las redes se convirtieron en un emotivo escaparate de homenajes a ese gran dibujante, humorista y fil\u00f3sofo de las verdades cotidianas m\u00e1s profundas. Cada contribuci\u00f3n subrayaba la manera que hab\u00eda tenido Quino (con su genial Mafalda como exponente m\u00e1ximo) de acompa\u00f1ar nuestras vidas, la manera de expresar de &#8230; <a title=\"Compartir a Mafalda\" class=\"read-more\" href=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2020\/10\/05\/compartir-a-mafalda\/\" aria-label=\"Leer m\u00e1s sobre Compartir a Mafalda\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[72,172],"tags":[],"class_list":["post-7467","post","type-post","status-publish","format-standard","hentry","category-contrastes","category-humor"],"_links":{"self":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/7467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/comments?post=7467"}],"version-history":[{"count":0,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/7467\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/media?parent=7467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/categories?post=7467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/tags?post=7467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}