{"id":7636,"date":"2021-02-12T12:37:06","date_gmt":"2021-02-12T11:37:06","guid":{"rendered":"https:\/\/www.urbinavolant.com\/verbavolant\/?p=7636"},"modified":"2021-02-12T18:07:06","modified_gmt":"2021-02-12T17:07:06","slug":"historias-de-alumnos-carta-semipublica-para-antonio","status":"publish","type":"post","link":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2021\/02\/12\/historias-de-alumnos-carta-semipublica-para-antonio\/","title":{"rendered":"Historias de alumnos. Carta semip\u00fablica para Antonio"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"433\" src=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2021\/02\/49801915398_60840a36b2_c-1.jpg\" alt=\"\" class=\"wp-image-7641\" srcset=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2021\/02\/49801915398_60840a36b2_c-1.jpg 800w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2021\/02\/49801915398_60840a36b2_c-1-300x162.jpg 300w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2021\/02\/49801915398_60840a36b2_c-1-768x416.jpg 768w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2021\/02\/49801915398_60840a36b2_c-1-624x338.jpg 624w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p>Tal y como comentaba ayer, me apetec\u00eda, por un lado, felicitar a Nerea no tanto por cumplir 37 a\u00f1os como por aglutinar tantos sentimientos y experiencias y tener esa manera tan estupenda de expresarlos. Y, por otro, contestar a un mensaje de correo que me escribi\u00f3 Antonio.<\/p>\n\n\n\n<p>Vaya por delante una cosa: me hace una grand\u00edsima ilusi\u00f3n que mis alumnos, actuales, antiguos y remotos, me escriban \u2014en el formato que sea, por la v\u00eda que sea\u2014 para contarme cosas de ellos, de m\u00ed, de cosas pasadas y de las cosas que nos pasan ahora, de lo que piensan que va a pasar y que nos gusta o nos afecta o nos importa.<\/p>\n\n\n\n<p>La casualidad hizo que, unos d\u00edas atr\u00e1s, recibiera un wasap de, \u00c1ngel, uno de los amigos y compa\u00f1eros de clase de Antonio. \u00c1ngel ha pasado \u00abal otro lado\u00bb y ahora es profe. Me hace muy feliz que seamos ahora colegas, fil\u00f3logos y que coincidamos en reuniones, aunque sea virtuales, para cosas relacionadas con el mundo acad\u00e9mico. Y, hace muy poco, Antonio me escribi\u00f3 un correo electr\u00f3nico, del que voy a hablar (parcialmente, lo que se pueda) aqu\u00ed y al que dar\u00e9 contestaci\u00f3n privada y merecida.<\/p>\n\n\n\n<p>Antes de nada, os convendr\u00eda recordar qui\u00e9n es Antonio:<\/p>\n\n\n\n<p><blockquote class=\"wp-embedded-content\" data-secret=\"z5X86W7CWT\"><a href=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2019\/03\/26\/historias-de-alumnos-el-chico-al-que-pillo-desnudo-la-policia-en-una-piscina-de-madrugada\/\">Historias de alumnos: el chico al que pill\u00f3 desnudo la polic\u00eda en una piscina de madrugada<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abHistorias de alumnos: el chico al que pill\u00f3 desnudo la polic\u00eda en una piscina de madrugada\u00bb \u2014 Verba Volant\" src=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2019\/03\/26\/historias-de-alumnos-el-chico-al-que-pillo-desnudo-la-policia-en-una-piscina-de-madrugada\/embed\/#?secret=QbN3BxMSiy#?secret=z5X86W7CWT\" data-secret=\"z5X86W7CWT\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p>Dec\u00eda que hab\u00eda recibido un correo de Antonio. Me dice que ha venido escribiendo a familiares y amigos desde Navidad y que, ahora, me ha llegado el turno a m\u00ed. Desvel\u00f3 aqu\u00ed, naturalmente, solo lo que puedo contar.<\/p>\n\n\n\n<p>Su manera de empezar demuestra que me conoce bien:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Bueno, solo quer\u00eda saludarte y preguntarte c\u00f3mo  est\u00e1s, d\u00f3nde pones las manos y en tu caso, m\u00e1s importante, d\u00f3nde  pones la cabeza.<\/p><\/blockquote>\n\n\n\n<p>Antonio sabe mi cuerpo va por un lado y mi cabeza por otro. O, lo m\u00e1s importante, que mi cabeza va a su bola, por mucho que tenga una mente cuadriculada en el sentido m\u00e1s estricto y que tienda a salirse por sus m\u00e1rgenes en su sentido m\u00e1s extravagante. <\/p>\n\n\n\n<p>El correo es un repaso por el cine, por la literatura y por las cosas del presente m\u00e1s inmediato, ese que est\u00e1 a ras de suelo. Antonio es rebelde y d\u00edscolo y provocador y me suelta, as\u00ed de primeras, que ha dejado de gustarle <em>Blade Runner<\/em>. \u00c9l sabe que ese es un golpe bajo, una noticia que solamente puede comunicarse cara a cara. Que esa pel\u00edcula, para m\u00ed, condensa todas las pel\u00edculas, las vidas, nuestras vidas en todas sus versiones (las de la pel\u00edcula, las de nuestras vidas). Pero yo no le voy a contestar que un d\u00eda, cuando volvamos a coincidir ese cogollito de estrellas de esa clase m\u00e1gica en la que estuvimos tantas horas, les invito a ver <em>Blade Runner 2049<\/em> a todos ellos para convencer a Antonio de que el viaje por los replicantes, que quiz\u00e1s soy yo, que quiz\u00e1s es \u00e9l, que quiz\u00e1s somos nosotros, sigue mereciendo la pena.<\/p>\n\n\n\n<p>Eso s\u00ed, a rengl\u00f3n seguido, me comenta que sigue viendo cine y disfrutando. Quiz\u00e1s no hay nada m\u00e1s hermoso que te digan que he aportado una diminuta semilla para disfrutar un poco m\u00e1s de las ficciones. Antonio y casi todos los que pasaron por mis clases en bachillerato saben lo que es la ficci\u00f3n para m\u00ed, una cuesti\u00f3n de principios y de finales, pero nunca de tibiezas, nunca de t\u00e9rminos medios. La \u00fanica manera que tenemos de comprender el mundo o de incomprenderlo y rebelarnos. Una vez m\u00e1s.<\/p>\n\n\n\n<p>Me dice que sigue leyendo a Lorca y que lo hace en voz alta. Que ha descubierto que los libros est\u00e1n hechos para leerlos as\u00ed, en voz alta. As\u00ed, un libro se lee y se escucha y tiene eco. Yo voy a hacer una confesi\u00f3n aqu\u00ed. Como me leer\u00e1n pocos, as\u00ed no se entera casi nadie: encant\u00e1ndome Garc\u00eda M\u00e1rquez, me cost\u00f3 mucho entrar por <em>Cien a\u00f1os de soledad<\/em>, no me pregunt\u00e9is por que. Un d\u00eda, dar clase me salv\u00f3 (una vez m\u00e1s): le\u00ed un pasaje de la novela y las palabras empezaron a cobrar una forma, una sinuosidad y unas sugerencias en las que comprend\u00ed, a la vez que ellos, por primera vez, que estaba ante una obra maestra y no solo un nombre ilustre.<\/p>\n\n\n\n<p>Dice Antonio que le gustar\u00eda leer m\u00e1s teatro, pero que no logra engancharle. El teatro, si es posible, hay que verlo y escucharlo. Recuerdo, sin embargo, ese maravilloso suced\u00e1neo cuando \u00edbamos repartiendo papeles para <em>La vida es sue\u00f1o<\/em> o para <em>Hamlet<\/em> o para <em>Tres sombreros de copa<\/em> y la magia cobraba todo su sentido. \u00c9ramos nosotros y ellos. Nuestra vida era la suya y la suya la hac\u00edamos nuestra, perdidos en prisiones, en destinos, en venganzas, en intrigas, en juegos de malabares en los que siempre se cae un sombrero.<\/p>\n\n\n\n<p>Y acabo como acaba (casi) Antonio, para contaros lo que hace ahora:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Estoy recogiendo aceitunas en Ja\u00e9n. Ahorita barri\u00e9ndolas del suelo. Qu\u00e9 locura.<\/p><\/blockquote>\n\n\n\n<p>Qu\u00e9 locura, Antonio, qu\u00e9 locura. Recoger esas perlas, tan deliciosas, con tanto trabajo. Me gusta imaginarte con la espalda doblada, con esfuerzo. Lo mismo que me ha gustado recibir todas tus palabras.<\/p>\n\n\n\n<p style=\"font-size:14px\">Esta entrada pertenece a la serie&nbsp;<em><a rel=\"noreferrer noopener\" href=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/tag\/historias-de-alumnos\/\" target=\"_blank\">Historias de alumnos<\/a><\/em>. Para salvaguardar las identidades, los nombres no son los reales y puede que se cambien algunas circunstancias contextuales, si ello es necesario para no revelar el secreto profesional. Tambi\u00e9n es conveniente recordar que, como puede suponerse, las historias se cuentan aqu\u00ed de una manera resumida y que, en la vida real, tuvieron muchos m\u00e1s matices.&nbsp;Con imagen de <a href=\"https:\/\/flic.kr\/p\/2iSPQnL\" target=\"_blank\" rel=\"noreferrer noopener\">Tom\u00e1s Hornos<\/a>.<\/p>\n\n\n\n<div>&nbsp;<\/div>\n\n\n\n\n\n<div>&nbsp;<\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Tal y como comentaba ayer, me apetec\u00eda, por un lado, felicitar a Nerea no tanto por cumplir 37 a\u00f1os como por aglutinar tantos sentimientos y experiencias y tener esa manera tan estupenda de expresarlos. Y, por otro, contestar a un mensaje de correo que me escribi\u00f3 Antonio. Vaya por delante una cosa: me hace una &#8230; <a title=\"Historias de alumnos. Carta semip\u00fablica para Antonio\" class=\"read-more\" href=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2021\/02\/12\/historias-de-alumnos-carta-semipublica-para-antonio\/\" aria-label=\"Leer m\u00e1s sobre Historias de alumnos. Carta semip\u00fablica para Antonio\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[59,44,114],"tags":[166],"class_list":["post-7636","post","type-post","status-publish","format-standard","hentry","category-cine","category-comparaciones","category-lectura","tag-historias-de-alumnos"],"_links":{"self":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/7636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/comments?post=7636"}],"version-history":[{"count":0,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/7636\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/media?parent=7636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/categories?post=7636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/tags?post=7636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}