{"id":8078,"date":"2023-06-21T18:15:04","date_gmt":"2023-06-21T17:15:04","guid":{"rendered":"https:\/\/www.urbinavolant.com\/verbavolant\/?p=8078"},"modified":"2023-06-21T18:15:34","modified_gmt":"2023-06-21T17:15:34","slug":"montones-de-vida","status":"publish","type":"post","link":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2023\/06\/21\/montones-de-vida\/","title":{"rendered":"Montones de vida"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/flic.kr\/p\/2mnC7vU\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2023\/06\/51440520270_b8c64e5232_c.jpg\" alt=\"\" class=\"wp-image-8080\" srcset=\"https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2023\/06\/51440520270_b8c64e5232_c.jpg 800w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2023\/06\/51440520270_b8c64e5232_c-300x300.jpg 300w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2023\/06\/51440520270_b8c64e5232_c-290x290.jpg 290w, https:\/\/www.urbinavolant.com\/verbavolant\/wp-content\/uploads\/2023\/06\/51440520270_b8c64e5232_c-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>\u00abVeo los montones de mi vida y no los reconozco\u00bb, dice Abe Weissman, el padre de Midge, en <em>The Marvelous Mrs. Maisel<\/em> (temporada 6, episodio 8).&nbsp;Es una manera de revisar la vida sin \u00e1nimos de linealidades ni de  circularidades, la vida como acumulaci\u00f3n de unas pocas cosas, unos pocos hechos, unos pocos personajes, unos pocos momentos que, grano a grano, conforman nuestra vida, que no s\u00e9 yo si es nuestra vida o, m\u00e1s bien, nuestras vidas.<\/p>\n\n\n\n<p>No s\u00e9 si es el momento de ponerse filos\u00f3fico, pero, en el fondo, toda reflexi\u00f3n sobre nosotros, lo que nos pasa o pensamos que nos pasa, es una reflexi\u00f3n sobre el \u00abyo\u00bb. Y el \u00abyo\u00bb es una de las cosas m\u00e1s dif\u00edciles de discernir. De hecho, me encanta las extensiones que hizo Freud sobre el \u00abyo\u00bb, el \u00abs\u00faper-yo\u00bb y el \u00abello\u00bb. Algo que somos, algo que est\u00e1 por encima de nosotros, algo que est\u00e1 tan por encima de nosotros que hemos de definirlo de manera muy lejana con un pronombre que no es nuestro porque es una pulsi\u00f3n humana. Demasiado humana, dir\u00eda Nietzsche. El yo no puede entenderse, solo diluirse.<\/p>\n\n\n\n<p>La mejor manera de mirarnos el \u00abyo\u00bb es contemplarlo con el convencimiento de que somos eso, montones de vida. A veces, ni siquiera parecen nuestros. A veces, ni siquiera lo fueron, puesto que nos los hemos inventado, nos los han inculcado o han sido elemento part\u00edcipe de esa gran confabulaci\u00f3n que son nuestras vidas, a mitad de camino entre replicantes sin conocimiento de causa y actores en un show de Truman en el que todav\u00eda no hemos llegado a comprobar que las casualidades no existen.<\/p>\n\n\n\n<p>Me odio por haber querido escribir una cosa en el primer p\u00e1rrafo y haberlo desvirtuado con la sesera. Lo que me hubiese gustado escribir es que la segunda temporada de <em>The Marvelous Mrs. Maisel<\/em> es magistral. La considero as\u00ed porque, a diferencia de en el cine, no me suelen gustar las series en forma de comedia, que tienden a la situaci\u00f3n estereotipada alrededor de un sof\u00e1, de un sal\u00f3n, de un caf\u00e9. Pero <em>The Marvelous Mrs. Maisel<\/em> es la comedia m\u00e1s c\u00f3mica y, por lo tanto, menos c\u00f3mica que he visto. Esa comedia que se escapa de los quicios para convertirse en conciencia de destino y, por lo tanto, consciencia de nosotros mismos, que nos vamos viendo representados. Es imposible hacerlo solo con uno de los personajes, como ocurre en la mayor parte de las obras grandes.<\/p>\n\n\n\n<p>Siendo tan diferentes, nunca he visto series tan similares (y no solo por la \u00e9poca) como <em>Mrs. Maisel<\/em> y <em>Mad Men<\/em>. Representando mundos casi opuestos y caracteres supuestamente contradictorios entre s\u00ed, beben en las mismas fuentes de la verdad, que est\u00e1n en el humor \u00e1cido y en la promoci\u00f3n de marcas y productos que esconden y evidencian la verdad de lo que somos. Pero hoy no toca explicar estas comparaciones.<\/p>\n\n\n\n<p>Siento asco por estos p\u00e1rrafos que escribo porque estoy haciendo algo que no quiero hacer. Quer\u00eda escribir algo sencillamente profundo y breve sobre una idea que salt\u00f3 desde la tele hasta la cabeza, como la pulga que te hace rascar y rascar hasta que sangras. Y lo \u00fanico que estoy haciendo es una muestra de lo \u00fanico que s\u00e9 hacer, ponerme en el escaparate de las cosas que m\u00e1s odio y ser totalmente incapaz de mostrar lo poco que puedo ser o que alcanzo a pensar.<\/p>\n\n\n\n<p>Pero una cosa es cierta: que la vida esta hecha con montones y que, al echar la vista atr\u00e1s, vemos una acumulaci\u00f3n de cosas que pensaban que constitu\u00edan vidas.<\/p>\n\n\n\n<p>Y no son m\u00e1s que polvo.<\/p>\n\n\n\n<p>Con imagen de <a rel=\"noreferrer noopener\" href=\"https:\/\/www.flickr.com\/photos\/kosmulski_origami\/\" target=\"_blank\">Michal Kosmulski<\/a>.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abVeo los montones de mi vida y no los reconozco\u00bb, dice Abe Weissman, el padre de Midge, en The Marvelous Mrs. Maisel (temporada 6, episodio 8).&nbsp;Es una manera de revisar la vida sin \u00e1nimos de linealidades ni de circularidades, la vida como acumulaci\u00f3n de unas pocas cosas, unos pocos hechos, unos pocos personajes, unos pocos &#8230; <a title=\"Montones de vida\" class=\"read-more\" href=\"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/2023\/06\/21\/montones-de-vida\/\" aria-label=\"Leer m\u00e1s sobre Montones de vida\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[44,72,61,65,107,1],"tags":[],"class_list":["post-8078","post","type-post","status-publish","format-standard","hentry","category-comparaciones","category-contrastes","category-laberintos","category-sentido","category-series","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/8078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/comments?post=8078"}],"version-history":[{"count":3,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/8078\/revisions"}],"predecessor-version":[{"id":8082,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/posts\/8078\/revisions\/8082"}],"wp:attachment":[{"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/media?parent=8078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/categories?post=8078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.urbinavolant.com\/verbavolant\/index.php\/wp-json\/wp\/v2\/tags?post=8078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}